{"id":2219,"date":"2017-11-13T18:18:09","date_gmt":"2017-11-14T00:18:09","guid":{"rendered":"https:\/\/ambsanjose.esteri.it\/news\/dall_ambasciata\/2017\/11\/sistema-pubblico-per-la-gestione\/"},"modified":"2017-11-13T18:18:09","modified_gmt":"2017-11-14T00:18:09","slug":"sistema-pubblico-per-la-gestione","status":"publish","type":"post","link":"https:\/\/ambsanjose.esteri.it\/it\/news\/dall_ambasciata\/2017\/11\/sistema-pubblico-per-la-gestione\/","title":{"rendered":"Sistema pubblico per la gestione dell&#8217;identita&#8217; digitale di cittadini ed imprese (SPID)"},"content":{"rendered":"<p>Lo SPID e&#8217; il sistema di autenticazione che permette\u00a0a cittadini e imprese di accedere con un&#8217;identita&#8217; digitale unica ai servizi online della Pubblica Amministrazione e dei privati aderenti.<\/p>\n<p>I cittadini italiani possono ottenere lo SPID purche&#8217; abbiano a disposione i documenti necessari (tessera sanitaria con codice fiscale ed un documento di identita&#8217; valido emesso da una Autorita&#8217; italiana).<\/p>\n<p>I connazionali dotati di SPID, a partire dal 1 ottobre 2018,\u00a0potranno accedere ai servizi online erogati da un altro Paese UE.<\/p>\n<p>Per ulteriori dettagli e informazioni si prega di consultare l&#8217;allegato : &#8220;<a href=\"resource\/doc\/2017\/11\/spid2.pdf\">SPID<\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"Lo SPID e&#8217; il sistema di autenticazione che permette\u00a0a cittadini e imprese di accedere con un&#8217;identita&#8217; digitale unica ai servizi online della Pubblica Amministrazione e dei privati aderenti. I cittadini italiani possono ottenere lo SPID purche&#8217; abbiano a disposione i documenti necessari (tessera sanitaria con codice fiscale ed un documento di identita&#8217; valido emesso da [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2219","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":0,"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2219\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2219"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambsanjose.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}